{"id":6322,"date":"2024-04-15T22:32:18","date_gmt":"2024-04-15T22:32:18","guid":{"rendered":"https:\/\/pmi.tech\/?page_id=6322"},"modified":"2024-06-11T15:46:51","modified_gmt":"2024-06-11T15:46:51","slug":"cobertura","status":"publish","type":"page","link":"https:\/\/pmi-americas.com\/en\/cobertura\/","title":{"rendered":"Coverage"},"content":{"rendered":"<div id=\"fws_6a97a8c8cc2ce\"  data-column-margin=\"default\" data-midnight=\"light\" data-top-percent=\"13%\" data-bottom-percent=\"13%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section parallax_section\"  style=\"padding-top: calc(100vw * 0.13); padding-bottom: calc(100vw * 0.13); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"true\"><div class=\"inner-wrap row-bg-layer using-image\" ><div class=\"row-bg viewport-desktop using-image using-bg-color\" data-parallax-speed=\"fast\" style=\"background-image: url(https:\/\/pmi-americas.com\/wp-content\/uploads\/2024\/04\/pmi-beyond-payments-cobertura-v1.jpg); background-position: left top; background-repeat: no-repeat; background-color: #ffffff; \"><\/div><\/div><div class=\"row-bg-overlay row-bg-layer\" style=\"background: #0a0a0a; background: linear-gradient(to bottom,#0a0a0a 0%,#002864 100%);  opacity: 0.5; \"><\/div><\/div>\n\t\t\t<div class=\"video-color-overlay row-bg-layer\" data-color=\"\"><\/div>\n\t\t\t\n\t\t\t<div class=\"nectar-video-wrap row-bg-layer\" data-bg-alignment=\"left top\">\n\t\t\t\t<div class=\"nectar-video-inner\">\n\t\t\t\t<video class=\"nectar-video-bg\" width=\"1800\" height=\"700\" preload=\"auto\" loop autoplay muted playsinline><\/video>    \t\t<\/div>\n\t\t\t <\/div>\n\n\t\t\t<div class=\"nectar-shape-divider-wrap\" style=\" height:200px;\"  data-height=\"200\" data-front=\"\" data-style=\"tilt_alt\" data-position=\"bottom\" ><svg class=\"nectar-shape-divider\" aria-hidden=\"true\" fill=\"#ffffff\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 100 10\" preserveaspectratio=\"none\"> <polygon points=\"100 10 100 0 -4 10\"><\/polygon> <\/svg><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div style=\"margin-top: 27px; \" class=\"vc_col-sm-6 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-split-heading\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"default\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"false\" data-has-fit-text=\"true\" ><div class=\"heading-line\" > <div><h3><span style=\"font-weight: 400\">At<\/span><b> PMI<\/b><span style=\"font-weight: 400\">, we are proud to offer state-of-the-art global and cross-border payment solutions.<\/span><\/h3> <\/div> <\/div><\/div><div id=\"fws_6a97a8c8cc9f9\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-10 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"300\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a97a8c8cd1aa\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"3%\" data-bottom-percent=\"7%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section\"  style=\"padding-top: calc(100vw * 0.03); padding-bottom: calc(100vw * 0.07); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #ffffff; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col has-animation no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-split-heading\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"default\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"false\" ><div class=\"heading-line\" > <div><h3 style=\"text-align: center\"><strong><span style=\"color: #002566\">Designed to meet the needs of companies of all sizes around the world.\u00a0<\/span><\/strong><\/h3> <\/div> <\/div><div class=\"heading-line\" > <div><h2><\/h2> <\/div> <\/div><div class=\"heading-line\" > <div><h2><\/h2> <\/div> <\/div><\/div><div class=\"nectar-split-heading\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"default\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"false\" ><div class=\"heading-line\" > <div><h4 style=\"text-align: center\"><span style=\"font-weight: 400;color: #002566\">We are committed to going the extra mile to make sure your payments are simple, secure and effective, wherever you are.<\/span><\/h4> <\/div> <\/div><div class=\"heading-line\" > <div><h3><\/h3> <\/div> <\/div><div class=\"heading-line\" > <div><h3><\/h3> <\/div> <\/div><\/div>\n\t<div class=\"wpb_raw_code wpb_content_element wpb_raw_html\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"map_wrapper\" id=\"map_wrapper_6425\">\n<div class=\"map_box\" style=\"max-width:2000px\">\n<div class=\"map_aspect_ratio\" style=\"padding-top:56%\" data-padding-top=\"56%\" data-padding-top-mobile=\"0%\">\n<div class=\"map_container\">\n<div class=\"map_render map_loading\" id=\"map_6425\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"explainer\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"6%\" data-bottom-percent=\"6%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section vc_row-o-equal-height vc_row-flex vc_row-o-content-middle\"  style=\"padding-top: calc(100vw * 0.06); padding-bottom: calc(100vw * 0.06); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col padding-2-percent inherit_tablet inherit_phone\"  data-padding-pos=\"right\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-split-heading\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"false\" ><h3 style=\" color: #59d477;\">En PMI vamos m\u00e1s all\u00e1 de las fronteras<\/h3><\/div>\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1713220595955\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>From our headquarters in Mexico, we have expanded our reach to serve the needs of companies around the world. With entities and offices strategically located in Miami, Mexico City, Bogota, Lima, Santiago de Chile, Buenos Aires, London and the United Kingdom. At PMI we go beyond borders to achieve and exceed your business goals.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col padding-2-percent inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"150%\" data-max-width-mobile=\"default\" data-border-radius=\"10px\" data-shadow=\"x_large_depth\" data-animation=\"fade-in-from-right\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"100\" height=\"588\" width=\"800\" data-animation=\"fade-in-from-right\" src=\"https:\/\/pmi-americas.com\/wp-content\/uploads\/2024\/04\/pmi-beyond-payments-cobertura-people.jpg\" alt=\"\" srcset=\"https:\/\/pmi-americas.com\/wp-content\/uploads\/2024\/04\/pmi-beyond-payments-cobertura-people.jpg 800w, https:\/\/pmi-americas.com\/wp-content\/uploads\/2024\/04\/pmi-beyond-payments-cobertura-people-300x221.jpg 300w, https:\/\/pmi-americas.com\/wp-content\/uploads\/2024\/04\/pmi-beyond-payments-cobertura-people-768x564.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"En PMI, nos enorgullece ofrecer soluciones de pagos globales y transfronterizas de vanguardia. Dise\u00f1adas para...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6322","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/pmi-americas.com\/en\/wp-json\/wp\/v2\/pages\/6322"}],"collection":[{"href":"https:\/\/pmi-americas.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pmi-americas.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pmi-americas.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pmi-americas.com\/en\/wp-json\/wp\/v2\/comments?post=6322"}],"version-history":[{"count":22,"href":"https:\/\/pmi-americas.com\/en\/wp-json\/wp\/v2\/pages\/6322\/revisions"}],"predecessor-version":[{"id":6926,"href":"https:\/\/pmi-americas.com\/en\/wp-json\/wp\/v2\/pages\/6322\/revisions\/6926"}],"wp:attachment":[{"href":"https:\/\/pmi-americas.com\/en\/wp-json\/wp\/v2\/media?parent=6322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}